{"id":233,"date":"2020-01-13T11:22:22","date_gmt":"2020-01-13T11:22:22","guid":{"rendered":"https:\/\/demosites.io\/web-agency-gb\/?p=12"},"modified":"2021-06-03T18:35:48","modified_gmt":"2021-06-03T17:35:48","slug":"versions-logotype","status":"publish","type":"post","link":"https:\/\/escapetoyourfuture.eu\/es\/versions-logotype\/","title":{"rendered":"Different versions of the logotype"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Project Summary<\/h2>\n\n\n\n<p>This is a european project funded by the Erasmus+ program. This project<br>intends to promote actions, to build contents, digital and physical instruments,<br>educational resources and to analyse the impact of innovative methodologies in<br>the target groups (youth workers and young people with ages between 18 and 30<br>years old) and stakeholders, rooted in a process of civilisational change (social,<br>political, economic and cultural). Always taking leverage of the individual skills<br>and competences of each partner and each individual, anchored by the best<br>research and state of the art practices.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Versions of the Logo<\/h2>\n\n\n\n<figure class=\"wp-block-gallery columns-2 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER.png\"><img decoding=\"async\" width=\"800\" height=\"498\" src=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER.png\" alt=\"\" data-id=\"775\" data-full-url=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER.png\" data-link=\"https:\/\/escapetoyourfuture.eu\/2020\/01\/13\/web-design-trends-for-2020\/logopg_winner\/\" class=\"wp-image-775\" srcset=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER.png 800w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER-300x187.png 300w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/logoPG_WINNER-768x478.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2.png\"><img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2.png\" alt=\"\" data-id=\"772\" data-full-url=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2.png\" data-link=\"https:\/\/escapetoyourfuture.eu\/2020\/01\/13\/web-design-trends-for-2020\/attachment\/2\/\" class=\"wp-image-772\" srcset=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2.png 800w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2-300x188.png 300w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/2-768x480.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3.png\"><img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3.png\" alt=\"\" data-id=\"773\" data-full-url=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3.png\" data-link=\"https:\/\/escapetoyourfuture.eu\/2020\/01\/13\/web-design-trends-for-2020\/attachment\/3\/\" class=\"wp-image-773\" srcset=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3.png 800w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3-300x188.png 300w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/3-768x480.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4.png\"><img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4.png\" alt=\"\" data-id=\"774\" data-full-url=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4.png\" data-link=\"https:\/\/escapetoyourfuture.eu\/2020\/01\/13\/web-design-trends-for-2020\/attachment\/4\/\" class=\"wp-image-774\" srcset=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4.png 800w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4-300x188.png 300w, https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/4-768x480.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-default\"><a class=\"wp-block-button__link has-nv-site-bg-color has-neve-link-hover-color-background-color has-text-color has-background\" href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/06\/Logo_Versions.zip\" style=\"border-radius:2px\" target=\"_blank\" rel=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/Logo_Versions.pdf noopener\">DOWNLOAD .PDF\/.SVG (89KB)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-nv-site-bg-color has-nv-c-1-background-color has-text-color has-background\" href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/Logo_Versions.png\" style=\"border-radius:2px\" target=\"_blank\" rel=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/Logo_Versions.png noopener\">DOWNLOAD .PNG (66kb)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/escapetoyourfuture.eu\/wp-content\/uploads\/2021\/05\/Logo_Versions.jpg\" target=\"_blank\" rel=\"noreferrer noopener\">DOWNLOAD .JPG (189kb)<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Project Summary This is a european project funded by the Erasmus+ program. This projectintends to promote actions, to build contents, digital and physical instruments,educational resources and to analyse the impact of innovative methodologies inthe target groups (youth workers and young people with ages between 18 and 30years old) and stakeholders, rooted in a process of&hellip;&nbsp;<a href=\"https:\/\/escapetoyourfuture.eu\/es\/versions-logotype\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Different versions of the logotype<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"off","neve_post_elements_order":"[\"title\",\"meta\",\"content\",\"tags\",\"comments\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press"],"_links":{"self":[{"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/posts\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/comments?post=233"}],"version-history":[{"count":13,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/posts\/233\/revisions"}],"predecessor-version":[{"id":850,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/posts\/233\/revisions\/850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/media\/806"}],"wp:attachment":[{"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/media?parent=233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/categories?post=233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escapetoyourfuture.eu\/es\/wp-json\/wp\/v2\/tags?post=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}